{"id":754972,"date":"2026-08-05T22:16:00","date_gmt":"2026-08-05T22:16:00","guid":{"rendered":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/"},"modified":"2026-09-01T12:00:16","modified_gmt":"2026-09-01T09:00:16","slug":"senzor-presiune-ulei-hella-6zl009600-041","status":"publish","type":"product","link":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/","title":{"rendered":"Senzor presiune ulei HELLA 6ZL009600-041"},"content":{"rendered":"<p>An fabricatie de la: 201001An fabricatie pana la: 201012Corespunde piesei originale- ca si culoare: gri, maroDeschidere cheie: 21Dimensiune filet: M16x1,5Functie comutator combinat: DeschizatorNum\u0103rul conexiunilor cu muf\u0103: 1Presiune [bar]: 0,5Tensiune [V]: 12Tip filet: cu filet metric<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: HELLA Cod producator: 6ZL009600-041<\/p>\n","protected":false},"featured_media":754973,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-754972","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senzor presiune ulei HELLA 6ZL009600-041 VOLVO | Cod - Autorival<\/title>\n<meta name=\"description\" content=\"\u26a1 Senzor presiune ulei HELLA 6ZL009600-041. Produc\u0103tor: HELLA. Cod: 6ZL009600-041. Pre\u021b: 37.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senzor presiune ulei HELLA 6ZL009600-041 VOLVO | Cod - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Senzor presiune ulei HELLA 6ZL009600-041. Produc\u0103tor: HELLA. Cod: 6ZL009600-041. Pre\u021b: 37.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/\" \/>\n<meta property=\"og:site_name\" content=\"VOLVO\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3884938_6zl_009_600-041.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Senzor presiune ulei HELLA 6ZL009600-041 VOLVO | Cod - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Senzor presiune ulei HELLA 6ZL009600-041. Produc\u0103tor: HELLA. Cod: 6ZL009600-041. Pre\u021b: 37.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/senzor-presiune-ulei-hella-6zl009600-041\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/senzor-presiune-ulei-hella-6zl009600-041\\\/\",\"name\":\"Senzor presiune ulei HELLA 6ZL009600-041 VOLVO | Cod - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/senzor-presiune-ulei-hella-6zl009600-041\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/senzor-presiune-ulei-hella-6zl009600-041\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/08\\\/3884938_6zl_009_600-041.jpg\",\"datePublished\":\"2026-08-05T22:16:00+00:00\",\"dateModified\":\"2026-09-01T09:00:16+00:00\",\"description\":\"\u26a1 Senzor presiune ulei HELLA 6ZL009600-041. Produc\u0103tor: HELLA. Cod: 6ZL009600-041. Pre\u021b: 37.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/senzor-presiune-ulei-hella-6zl009600-041\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/senzor-presiune-ulei-hella-6zl009600-041\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/senzor-presiune-ulei-hella-6zl009600-041\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/08\\\/3884938_6zl_009_600-041.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/08\\\/3884938_6zl_009_600-041.jpg\",\"width\":600,\"height\":400,\"caption\":\"Senzor presiune ulei HELLA 6ZL009600-041 \u2013 VOLVO | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/senzor-presiune-ulei-hella-6zl009600-041\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto VOLVO\",\"item\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senzor presiune ulei HELLA 6ZL009600-041\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/\",\"name\":\"VOLVO\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senzor presiune ulei HELLA 6ZL009600-041 VOLVO | Cod - Autorival","description":"\u26a1 Senzor presiune ulei HELLA 6ZL009600-041. Produc\u0103tor: HELLA. Cod: 6ZL009600-041. Pre\u021b: 37.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Senzor presiune ulei HELLA 6ZL009600-041 VOLVO | Cod - Autorival","og_description":"\u26a1 Senzor presiune ulei HELLA 6ZL009600-041. Produc\u0103tor: HELLA. Cod: 6ZL009600-041. Pre\u021b: 37.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/","og_site_name":"VOLVO","article_modified_time":"2026-09-01T09:00:16+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3884938_6zl_009_600-041.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Senzor presiune ulei HELLA 6ZL009600-041 VOLVO | Cod - Autorival","twitter_description":"\u26a1 Senzor presiune ulei HELLA 6ZL009600-041. Produc\u0103tor: HELLA. Cod: 6ZL009600-041. Pre\u021b: 37.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/","url":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/","name":"Senzor presiune ulei HELLA 6ZL009600-041 VOLVO | Cod - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/volvo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3884938_6zl_009_600-041.jpg","datePublished":"2026-08-05T22:16:00+00:00","dateModified":"2026-09-01T09:00:16+00:00","description":"\u26a1 Senzor presiune ulei HELLA 6ZL009600-041. Produc\u0103tor: HELLA. Cod: 6ZL009600-041. Pre\u021b: 37.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/#primaryimage","url":"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3884938_6zl_009_600-041.jpg","contentUrl":"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3884938_6zl_009_600-041.jpg","width":600,"height":400,"caption":"Senzor presiune ulei HELLA 6ZL009600-041 \u2013 VOLVO | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/volvo\/product\/senzor-presiune-ulei-hella-6zl009600-041\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/volvo\/"},{"@type":"ListItem","position":2,"name":"Piese auto VOLVO","item":"https:\/\/autorival.ro\/volvo\/"},{"@type":"ListItem","position":3,"name":"Senzor presiune ulei HELLA 6ZL009600-041"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/volvo\/#website","url":"https:\/\/autorival.ro\/volvo\/","name":"VOLVO","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/volvo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product\/754972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/comments?post=754972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/media\/754973"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/media?parent=754972"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product_brand?post=754972"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product_cat?post=754972"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product_tag?post=754972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}