{"id":743079,"date":"2026-08-05T21:27:27","date_gmt":"2026-08-05T21:27:27","guid":{"rendered":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/"},"modified":"2026-09-01T11:51:06","modified_gmt":"2026-09-01T08:51:06","slug":"pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335","status":"publish","type":"product","link":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/","title":{"rendered":"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335"},"content":{"rendered":"<p>Echipament vehicul: Pentru autovehicole fara Functie-Strat-StopMod de operare: electricNumar motor TECDOC: 28542Tensiune [V]: 12<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: MAXGEAR Cod producator: 47-0335<\/p>\n","protected":false},"featured_media":743080,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-743079","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pompa de apa instalatia de incalzire independenta MAXGEAR\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335. Produc\u0103tor: MAXGEAR. Cod: 47-0335. Pre\u021b: 316 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335 VOLVO | Cod - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335. Produc\u0103tor: MAXGEAR. Cod: 47-0335. Pre\u021b: 316 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/\" \/>\n<meta property=\"og:site_name\" content=\"VOLVO\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T08:51:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3736133_47-0335_1_large.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335 VOLVO | Cod - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335. Produc\u0103tor: MAXGEAR. Cod: 47-0335. Pre\u021b: 316 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\\\/\",\"name\":\"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335 VOLVO | Cod - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/08\\\/3736133_47-0335_1_large.jpg\",\"datePublished\":\"2026-08-05T21:27:27+00:00\",\"dateModified\":\"2026-09-01T08:51:06+00:00\",\"description\":\"\u26a1 Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335. Produc\u0103tor: MAXGEAR. Cod: 47-0335. Pre\u021b: 316 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/08\\\/3736133_47-0335_1_large.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/08\\\/3736133_47-0335_1_large.jpg\",\"width\":634,\"height\":400,\"caption\":\"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335 \u2013 VOLVO | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/product\\\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto VOLVO\",\"item\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/\",\"name\":\"VOLVO\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/volvo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pompa de apa instalatia de incalzire independenta MAXGEAR\u2026","description":"\u26a1 Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335. Produc\u0103tor: MAXGEAR. Cod: 47-0335. Pre\u021b: 316 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335 VOLVO | Cod - Autorival","og_description":"\u26a1 Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335. Produc\u0103tor: MAXGEAR. Cod: 47-0335. Pre\u021b: 316 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/","og_site_name":"VOLVO","article_modified_time":"2026-09-01T08:51:06+00:00","og_image":[{"width":634,"height":400,"url":"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3736133_47-0335_1_large.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335 VOLVO | Cod - Autorival","twitter_description":"\u26a1 Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335. Produc\u0103tor: MAXGEAR. Cod: 47-0335. Pre\u021b: 316 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/","url":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/","name":"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335 VOLVO | Cod - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/volvo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3736133_47-0335_1_large.jpg","datePublished":"2026-08-05T21:27:27+00:00","dateModified":"2026-09-01T08:51:06+00:00","description":"\u26a1 Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335. Produc\u0103tor: MAXGEAR. Cod: 47-0335. Pre\u021b: 316 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/#primaryimage","url":"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3736133_47-0335_1_large.jpg","contentUrl":"https:\/\/autorival.ro\/volvo\/wp-content\/uploads\/sites\/20\/2026\/08\/3736133_47-0335_1_large.jpg","width":634,"height":400,"caption":"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335 \u2013 VOLVO | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/volvo\/product\/pompa-de-apa-instalatia-de-incalzire-independenta-maxgear-47-0335\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/volvo\/"},{"@type":"ListItem","position":2,"name":"Piese auto VOLVO","item":"https:\/\/autorival.ro\/volvo\/"},{"@type":"ListItem","position":3,"name":"Pompa de apa instalatia de incalzire independenta MAXGEAR 47-0335"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/volvo\/#website","url":"https:\/\/autorival.ro\/volvo\/","name":"VOLVO","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/volvo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product\/743079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/comments?post=743079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/media\/743080"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/media?parent=743079"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product_brand?post=743079"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product_cat?post=743079"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/volvo\/wp-json\/wp\/v2\/product_tag?post=743079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}