{"id":2102850,"date":"2026-07-08T13:08:24","date_gmt":"2026-07-08T13:08:24","guid":{"rendered":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/"},"modified":"2026-09-01T14:45:34","modified_gmt":"2026-09-01T11:45:34","slug":"senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537","status":"publish","type":"product","link":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/","title":{"rendered":"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537"},"content":{"rendered":"<p>An fabricatie de la: 198709Dimensiune filet: 1\/8&#215;28 BSPT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: CALORSTAT BY VERNET Cod producator: WS2537<\/p>\n","protected":false},"featured_media":2102851,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-2102850","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537. Produc\u0103tor: CALORSTAT BY VERNET. Cod: WS2537. Pre\u021b: 60.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537 Toyota | Cod - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537. Produc\u0103tor: CALORSTAT BY VERNET. Cod: WS2537. Pre\u021b: 60.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/\" \/>\n<meta property=\"og:site_name\" content=\"Toyota\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T11:45:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3871638_ws2537.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537 Toyota | Cod - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537. Produc\u0103tor: CALORSTAT BY VERNET. Cod: WS2537. Pre\u021b: 60.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\\\/\",\"name\":\"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537 Toyota | Cod - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2026\\\/07\\\/3871638_ws2537.jpg\",\"datePublished\":\"2026-07-08T13:08:24+00:00\",\"dateModified\":\"2026-09-01T11:45:34+00:00\",\"description\":\"\u26a1 Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537. Produc\u0103tor: CALORSTAT BY VERNET. Cod: WS2537. Pre\u021b: 60.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2026\\\/07\\\/3871638_ws2537.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2026\\\/07\\\/3871638_ws2537.jpg\",\"width\":400,\"height\":400,\"caption\":\"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537 \u2013 Toyota | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TOYOTA\",\"item\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/\",\"name\":\"Toyota\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537\u2026","description":"\u26a1 Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537. Produc\u0103tor: CALORSTAT BY VERNET. Cod: WS2537. Pre\u021b: 60.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537 Toyota | Cod - Autorival","og_description":"\u26a1 Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537. Produc\u0103tor: CALORSTAT BY VERNET. Cod: WS2537. Pre\u021b: 60.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/","og_site_name":"Toyota","article_modified_time":"2026-09-01T11:45:34+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3871638_ws2537.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537 Toyota | Cod - Autorival","twitter_description":"\u26a1 Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537. Produc\u0103tor: CALORSTAT BY VERNET. Cod: WS2537. Pre\u021b: 60.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/","url":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/","name":"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537 Toyota | Cod - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/toyot\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3871638_ws2537.jpg","datePublished":"2026-07-08T13:08:24+00:00","dateModified":"2026-09-01T11:45:34+00:00","description":"\u26a1 Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537. Produc\u0103tor: CALORSTAT BY VERNET. Cod: WS2537. Pre\u021b: 60.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/#primaryimage","url":"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3871638_ws2537.jpg","contentUrl":"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3871638_ws2537.jpg","width":400,"height":400,"caption":"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537 \u2013 Toyota | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-temperatura-lichid-de-racire-calorstat-by-vernet-ws2537\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/toyot\/"},{"@type":"ListItem","position":2,"name":"TOYOTA","item":"https:\/\/autorival.ro\/toyot\/"},{"@type":"ListItem","position":3,"name":"Senzor temperatura lichid de racire CALORSTAT BY VERNET WS2537"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/toyot\/#website","url":"https:\/\/autorival.ro\/toyot\/","name":"Toyota","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/toyot\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product\/2102850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/comments?post=2102850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/media\/2102851"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/media?parent=2102850"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product_brand?post=2102850"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product_cat?post=2102850"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product_tag?post=2102850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}