{"id":2102554,"date":"2026-07-08T13:06:36","date_gmt":"2026-07-08T13:06:36","guid":{"rendered":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/"},"modified":"2026-09-01T14:45:19","modified_gmt":"2026-09-01T11:45:19","slug":"senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431","status":"publish","type":"product","link":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/","title":{"rendered":"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431"},"content":{"rendered":"<p>An fabricatie de la: 201504An fabricatie pana la: 201408Domeniul de frecven\u0163\u0103 [MHz]: 433Moment strangere [Nm]: 4Tip autovehicul: Land Cruiser, Land Cruiser Prado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: HELLA Cod producator: 6PP358139-431<\/p>\n","protected":false},"featured_media":2102555,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-2102554","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senzor sistem de control al presiunii pneuri HELLA\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431. Produc\u0103tor: HELLA. Cod: 6PP358139-431. Pre\u021b: 244 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431 Toyota | Cod - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431. Produc\u0103tor: HELLA. Cod: 6PP358139-431. Pre\u021b: 244 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/\" \/>\n<meta property=\"og:site_name\" content=\"Toyota\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T11:45:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3881940_358139431_diag_left_td_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431 Toyota | Cod - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431. Produc\u0103tor: HELLA. Cod: 6PP358139-431. Pre\u021b: 244 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\\\/\",\"name\":\"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431 Toyota | Cod - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2026\\\/07\\\/3881940_358139431_diag_left_td_1.jpg\",\"datePublished\":\"2026-07-08T13:06:36+00:00\",\"dateModified\":\"2026-09-01T11:45:19+00:00\",\"description\":\"\u26a1 Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431. Produc\u0103tor: HELLA. Cod: 6PP358139-431. Pre\u021b: 244 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2026\\\/07\\\/3881940_358139431_diag_left_td_1.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2026\\\/07\\\/3881940_358139431_diag_left_td_1.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431 \u2013 Toyota | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/produs\\\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TOYOTA\",\"item\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/\",\"name\":\"Toyota\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/toyot\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senzor sistem de control al presiunii pneuri HELLA\u2026","description":"\u26a1 Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431. Produc\u0103tor: HELLA. Cod: 6PP358139-431. Pre\u021b: 244 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431 Toyota | Cod - Autorival","og_description":"\u26a1 Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431. Produc\u0103tor: HELLA. Cod: 6PP358139-431. Pre\u021b: 244 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/","og_site_name":"Toyota","article_modified_time":"2026-09-01T11:45:19+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3881940_358139431_diag_left_td_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431 Toyota | Cod - Autorival","twitter_description":"\u26a1 Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431. Produc\u0103tor: HELLA. Cod: 6PP358139-431. Pre\u021b: 244 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/","url":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/","name":"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431 Toyota | Cod - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/toyot\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3881940_358139431_diag_left_td_1.jpg","datePublished":"2026-07-08T13:06:36+00:00","dateModified":"2026-09-01T11:45:19+00:00","description":"\u26a1 Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431. Produc\u0103tor: HELLA. Cod: 6PP358139-431. Pre\u021b: 244 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/#primaryimage","url":"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3881940_358139431_diag_left_td_1.jpg","contentUrl":"https:\/\/autorival.ro\/toyot\/wp-content\/uploads\/sites\/29\/2026\/07\/3881940_358139431_diag_left_td_1.jpg","width":1500,"height":1000,"caption":"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431 \u2013 Toyota | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/toyot\/produs\/senzor-sistem-de-control-al-presiunii-pneuri-hella-6pp358139-431\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/toyot\/"},{"@type":"ListItem","position":2,"name":"TOYOTA","item":"https:\/\/autorival.ro\/toyot\/"},{"@type":"ListItem","position":3,"name":"Senzor sistem de control al presiunii pneuri HELLA 6PP358139-431"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/toyot\/#website","url":"https:\/\/autorival.ro\/toyot\/","name":"Toyota","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/toyot\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product\/2102554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/comments?post=2102554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/media\/2102555"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/media?parent=2102554"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product_brand?post=2102554"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product_cat?post=2102554"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/toyot\/wp-json\/wp\/v2\/product_tag?post=2102554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}