{"id":724289,"date":"2026-08-01T02:03:06","date_gmt":"2026-08-01T02:03:06","guid":{"rendered":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/"},"modified":"2026-09-01T13:30:00","modified_gmt":"2026-09-01T10:30:00","slug":"senzor-presiune-supraalimentare-hella-6pp009400-281","status":"publish","type":"product","link":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/","title":{"rendered":"Senzor presiune supraalimentare HELLA 6PP009400-281"},"content":{"rendered":"<p>An fabricatie de la: 200804An fabricatie pana la: 200908Articol completare\/Info suplimentar 2: fara cabluArticol extins\/Informatii de extindere: cu etansareCod motor: H4M738, H4M750Numar bucati necesare: 1Numar informatii tehnice: 8200719629, 8200121800Numar motor TECDOC: 23553Num\u0103rul conexiunilor cu muf\u0103: 3pentru codul de tip: L8JB\/L8ME\/L8MVTip autovehicul: Clio Symbol, Clio Thalia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: HELLA Cod producator: 6PP009400-281<\/p>\n","protected":false},"featured_media":724290,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-724289","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senzor presiune supraalimentare HELLA 6PP009400-281 RENAULT\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Senzor presiune supraalimentare HELLA 6PP009400-281. Produc\u0103tor: HELLA. Cod: 6PP009400-281. Pre\u021b: 195.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senzor presiune supraalimentare HELLA 6PP009400-281 RENAULT | Cod - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Senzor presiune supraalimentare HELLA 6PP009400-281. Produc\u0103tor: HELLA. Cod: 6PP009400-281. Pre\u021b: 195.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/\" \/>\n<meta property=\"og:site_name\" content=\"RENAULT\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T10:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/3881757_6pp_009_400-281.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"597\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Senzor presiune supraalimentare HELLA 6PP009400-281 RENAULT | Cod - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Senzor presiune supraalimentare HELLA 6PP009400-281. Produc\u0103tor: HELLA. Cod: 6PP009400-281. Pre\u021b: 195.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-supraalimentare-hella-6pp009400-281\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-supraalimentare-hella-6pp009400-281\\\/\",\"name\":\"Senzor presiune supraalimentare HELLA 6PP009400-281 RENAULT | Cod - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-supraalimentare-hella-6pp009400-281\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-supraalimentare-hella-6pp009400-281\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/08\\\/3881757_6pp_009_400-281.jpg\",\"datePublished\":\"2026-08-01T02:03:06+00:00\",\"dateModified\":\"2026-09-01T10:30:00+00:00\",\"description\":\"\u26a1 Senzor presiune supraalimentare HELLA 6PP009400-281. Produc\u0103tor: HELLA. Cod: 6PP009400-281. Pre\u021b: 195.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-supraalimentare-hella-6pp009400-281\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-supraalimentare-hella-6pp009400-281\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-supraalimentare-hella-6pp009400-281\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/08\\\/3881757_6pp_009_400-281.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/08\\\/3881757_6pp_009_400-281.jpg\",\"width\":597,\"height\":400,\"caption\":\"Senzor presiune supraalimentare HELLA 6PP009400-281 \u2013 RENAULT | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-supraalimentare-hella-6pp009400-281\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto RENAULT\",\"item\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senzor presiune supraalimentare HELLA 6PP009400-281\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\",\"name\":\"RENAULT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senzor presiune supraalimentare HELLA 6PP009400-281 RENAULT\u2026","description":"\u26a1 Senzor presiune supraalimentare HELLA 6PP009400-281. Produc\u0103tor: HELLA. Cod: 6PP009400-281. Pre\u021b: 195.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Senzor presiune supraalimentare HELLA 6PP009400-281 RENAULT | Cod - Autorival","og_description":"\u26a1 Senzor presiune supraalimentare HELLA 6PP009400-281. Produc\u0103tor: HELLA. Cod: 6PP009400-281. Pre\u021b: 195.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/","og_site_name":"RENAULT","article_modified_time":"2026-09-01T10:30:00+00:00","og_image":[{"width":597,"height":400,"url":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/3881757_6pp_009_400-281.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Senzor presiune supraalimentare HELLA 6PP009400-281 RENAULT | Cod - Autorival","twitter_description":"\u26a1 Senzor presiune supraalimentare HELLA 6PP009400-281. Produc\u0103tor: HELLA. Cod: 6PP009400-281. Pre\u021b: 195.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/","url":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/","name":"Senzor presiune supraalimentare HELLA 6PP009400-281 RENAULT | Cod - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/renault\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/3881757_6pp_009_400-281.jpg","datePublished":"2026-08-01T02:03:06+00:00","dateModified":"2026-09-01T10:30:00+00:00","description":"\u26a1 Senzor presiune supraalimentare HELLA 6PP009400-281. Produc\u0103tor: HELLA. Cod: 6PP009400-281. Pre\u021b: 195.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/#primaryimage","url":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/3881757_6pp_009_400-281.jpg","contentUrl":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/3881757_6pp_009_400-281.jpg","width":597,"height":400,"caption":"Senzor presiune supraalimentare HELLA 6PP009400-281 \u2013 RENAULT | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-supraalimentare-hella-6pp009400-281\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/renault\/"},{"@type":"ListItem","position":2,"name":"Piese auto RENAULT","item":"https:\/\/autorival.ro\/renault\/"},{"@type":"ListItem","position":3,"name":"Senzor presiune supraalimentare HELLA 6PP009400-281"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/renault\/#website","url":"https:\/\/autorival.ro\/renault\/","name":"RENAULT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/renault\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product\/724289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/comments?post=724289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/media\/724290"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/media?parent=724289"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_brand?post=724289"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_cat?post=724289"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_tag?post=724289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}