{"id":723335,"date":"2026-08-01T01:59:16","date_gmt":"2026-08-01T01:59:16","guid":{"rendered":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/"},"modified":"2026-09-01T13:28:46","modified_gmt":"2026-09-01T10:28:46","slug":"senzor-presiune-aer-facet-10-3167","status":"publish","type":"product","link":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/","title":{"rendered":"Senzor presiune aer FACET 10.3167"},"content":{"rendered":"<p>Cod motor: F9Q803\/F9Q804\/F9Q816, F9Q818Numar motor TECDOC: 20391pentru codul de tip: JM15\/JM1DPresiune de la [kPA]: 45Presiune pana la [kPa]: 370Tensiune de ie\u0219ire de la [V]: 0,42Tensiune de ie\u0219ire p\u00e2n\u0103 la [V]: 4,74<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: FACET Cod producator: 10.3167<\/p>\n","protected":false},"featured_media":723336,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-723335","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senzor presiune aer FACET 10.3167 RENAULT | Cod - Autorival<\/title>\n<meta name=\"description\" content=\"\u26a1 Senzor presiune aer FACET 10.3167. Produc\u0103tor: FACET. Cod: 10.3167. Pre\u021b: 245.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senzor presiune aer FACET 10.3167 RENAULT | Cod - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Senzor presiune aer FACET 10.3167. Produc\u0103tor: FACET. Cod: 10.3167. Pre\u021b: 245.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/\" \/>\n<meta property=\"og:site_name\" content=\"RENAULT\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T10:28:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/2570593_10.3167-fa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"599\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Senzor presiune aer FACET 10.3167 RENAULT | Cod - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Senzor presiune aer FACET 10.3167. Produc\u0103tor: FACET. Cod: 10.3167. Pre\u021b: 245.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-aer-facet-10-3167\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-aer-facet-10-3167\\\/\",\"name\":\"Senzor presiune aer FACET 10.3167 RENAULT | Cod - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-aer-facet-10-3167\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-aer-facet-10-3167\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/08\\\/2570593_10.3167-fa.jpg\",\"datePublished\":\"2026-08-01T01:59:16+00:00\",\"dateModified\":\"2026-09-01T10:28:46+00:00\",\"description\":\"\u26a1 Senzor presiune aer FACET 10.3167. Produc\u0103tor: FACET. Cod: 10.3167. Pre\u021b: 245.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-aer-facet-10-3167\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-aer-facet-10-3167\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-aer-facet-10-3167\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/08\\\/2570593_10.3167-fa.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/08\\\/2570593_10.3167-fa.jpg\",\"width\":599,\"height\":399,\"caption\":\"Senzor presiune aer FACET 10.3167 \u2013 RENAULT | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/senzor-presiune-aer-facet-10-3167\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto RENAULT\",\"item\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senzor presiune aer FACET 10.3167\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\",\"name\":\"RENAULT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senzor presiune aer FACET 10.3167 RENAULT | Cod - Autorival","description":"\u26a1 Senzor presiune aer FACET 10.3167. Produc\u0103tor: FACET. Cod: 10.3167. Pre\u021b: 245.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Senzor presiune aer FACET 10.3167 RENAULT | Cod - Autorival","og_description":"\u26a1 Senzor presiune aer FACET 10.3167. Produc\u0103tor: FACET. Cod: 10.3167. Pre\u021b: 245.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/","og_site_name":"RENAULT","article_modified_time":"2026-09-01T10:28:46+00:00","og_image":[{"width":599,"height":399,"url":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/2570593_10.3167-fa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Senzor presiune aer FACET 10.3167 RENAULT | Cod - Autorival","twitter_description":"\u26a1 Senzor presiune aer FACET 10.3167. Produc\u0103tor: FACET. Cod: 10.3167. Pre\u021b: 245.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/","url":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/","name":"Senzor presiune aer FACET 10.3167 RENAULT | Cod - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/renault\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/2570593_10.3167-fa.jpg","datePublished":"2026-08-01T01:59:16+00:00","dateModified":"2026-09-01T10:28:46+00:00","description":"\u26a1 Senzor presiune aer FACET 10.3167. Produc\u0103tor: FACET. Cod: 10.3167. Pre\u021b: 245.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/#primaryimage","url":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/2570593_10.3167-fa.jpg","contentUrl":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/08\/2570593_10.3167-fa.jpg","width":599,"height":399,"caption":"Senzor presiune aer FACET 10.3167 \u2013 RENAULT | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/renault\/product\/senzor-presiune-aer-facet-10-3167\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/renault\/"},{"@type":"ListItem","position":2,"name":"Piese auto RENAULT","item":"https:\/\/autorival.ro\/renault\/"},{"@type":"ListItem","position":3,"name":"Senzor presiune aer FACET 10.3167"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/renault\/#website","url":"https:\/\/autorival.ro\/renault\/","name":"RENAULT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/renault\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product\/723335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/comments?post=723335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/media\/723336"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/media?parent=723335"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_brand?post=723335"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_cat?post=723335"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_tag?post=723335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}