{"id":617694,"date":"2026-07-31T20:13:46","date_gmt":"2026-07-31T20:13:46","guid":{"rendered":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/"},"modified":"2026-07-31T20:13:46","modified_gmt":"2026-07-31T20:13:46","slug":"bec-lampa-frana-lampa-spate-hella-8gd-004-772-123","status":"publish","type":"product","link":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/","title":{"rendered":"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123"},"content":{"rendered":"<p>Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123Calitate: 2Culoare bec incandescent: transparentPutere nominal\u0103 [W]: 21\/4Tensiune [V]: 12Tip ambalaj: ambalaj blisterTip inmatriculare: Verificat ECETIp lampa: P21\/4WVariant\u0103 de execu\u021bie soclu lamp\u0103 incandescent\u0103: BAZ15d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: HELLA Cod producator: 8GD 004 772-123<\/p>\n","protected":false},"featured_media":617695,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[4603],"product_cat":[],"product_tag":[],"class_list":{"0":"post-617694","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-hella","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123 RENAULT\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123. Produc\u0103tor: HELLA. Cod: 8GD 004 772-123. Pre\u021b: 22.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123 RENAULT | HELLA - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123. Produc\u0103tor: HELLA. Cod: 8GD 004 772-123. Pre\u021b: 22.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/\" \/>\n<meta property=\"og:site_name\" content=\"RENAULT\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3897538_8gd_004_772-123a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"597\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123 RENAULT | HELLA - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123. Produc\u0103tor: HELLA. Cod: 8GD 004 772-123. Pre\u021b: 22.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\\\/\",\"name\":\"Bec lampa frana \\\/ lampa spate HELLA 8GD 004 772-123 RENAULT | HELLA - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/07\\\/3897538_8gd_004_772-123a.jpg\",\"datePublished\":\"2026-07-31T20:13:46+00:00\",\"description\":\"\u26a1 Bec lampa frana \\\/ lampa spate HELLA 8GD 004 772-123. Produc\u0103tor: HELLA. Cod: 8GD 004 772-123. Pre\u021b: 22.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/07\\\/3897538_8gd_004_772-123a.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/07\\\/3897538_8gd_004_772-123a.jpg\",\"width\":597,\"height\":400,\"caption\":\"Bec lampa frana \\\/ lampa spate HELLA 8GD 004 772-123 \u2013 RENAULT | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto RENAULT\",\"item\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bec lampa frana \\\/ lampa spate HELLA 8GD 004 772-123\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\",\"name\":\"RENAULT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123 RENAULT\u2026","description":"\u26a1 Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123. Produc\u0103tor: HELLA. Cod: 8GD 004 772-123. Pre\u021b: 22.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123 RENAULT | HELLA - Autorival","og_description":"\u26a1 Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123. Produc\u0103tor: HELLA. Cod: 8GD 004 772-123. Pre\u021b: 22.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/","og_site_name":"RENAULT","og_image":[{"width":597,"height":400,"url":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3897538_8gd_004_772-123a.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123 RENAULT | HELLA - Autorival","twitter_description":"\u26a1 Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123. Produc\u0103tor: HELLA. Cod: 8GD 004 772-123. Pre\u021b: 22.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/","url":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/","name":"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123 RENAULT | HELLA - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/renault\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3897538_8gd_004_772-123a.jpg","datePublished":"2026-07-31T20:13:46+00:00","description":"\u26a1 Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123. Produc\u0103tor: HELLA. Cod: 8GD 004 772-123. Pre\u021b: 22.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/#primaryimage","url":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3897538_8gd_004_772-123a.jpg","contentUrl":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3897538_8gd_004_772-123a.jpg","width":597,"height":400,"caption":"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123 \u2013 RENAULT | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/renault\/product\/bec-lampa-frana-lampa-spate-hella-8gd-004-772-123\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/renault\/"},{"@type":"ListItem","position":2,"name":"Piese auto RENAULT","item":"https:\/\/autorival.ro\/renault\/"},{"@type":"ListItem","position":3,"name":"Bec lampa frana \/ lampa spate HELLA 8GD 004 772-123"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/renault\/#website","url":"https:\/\/autorival.ro\/renault\/","name":"RENAULT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/renault\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product\/617694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/comments?post=617694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/media\/617695"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/media?parent=617694"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_brand?post=617694"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_cat?post=617694"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_tag?post=617694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}