{"id":615204,"date":"2026-07-31T20:05:17","date_gmt":"2026-07-31T20:05:17","guid":{"rendered":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/"},"modified":"2026-07-31T20:05:17","modified_gmt":"2026-07-31T20:05:17","slug":"articulatie-coloana-de-directie-metalcaucho-00152","status":"publish","type":"product","link":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/","title":{"rendered":"Articulatie coloana de directie METALCAUCHO 00152"},"content":{"rendered":"<p>Articulatie coloana de directie METALCAUCHO 00152Diametru [mm]: 9Greutate [kg]: 0,09Lungime [mm]: 49,5Masa [g]: 90<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: METALCAUCHO Cod producator: 00152<\/p>\n","protected":false},"featured_media":615205,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[60],"product_cat":[],"product_tag":[],"class_list":{"0":"post-615204","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-metalcaucho","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Articulatie coloana de directie METALCAUCHO 00152 RENAULT\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Articulatie coloana de directie METALCAUCHO 00152. Produc\u0103tor: METALCAUCHO. Cod: 00152. Pre\u021b: 32.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Articulatie coloana de directie METALCAUCHO 00152 RENAULT | METALCAUCHO - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Articulatie coloana de directie METALCAUCHO 00152. Produc\u0103tor: METALCAUCHO. Cod: 00152. Pre\u021b: 32.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/\" \/>\n<meta property=\"og:site_name\" content=\"RENAULT\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3314048_00152_201018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Articulatie coloana de directie METALCAUCHO 00152 RENAULT | METALCAUCHO - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Articulatie coloana de directie METALCAUCHO 00152. Produc\u0103tor: METALCAUCHO. Cod: 00152. Pre\u021b: 32.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/articulatie-coloana-de-directie-metalcaucho-00152\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/articulatie-coloana-de-directie-metalcaucho-00152\\\/\",\"name\":\"Articulatie coloana de directie METALCAUCHO 00152 RENAULT | METALCAUCHO - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/articulatie-coloana-de-directie-metalcaucho-00152\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/articulatie-coloana-de-directie-metalcaucho-00152\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/07\\\/3314048_00152_201018.jpg\",\"datePublished\":\"2026-07-31T20:05:17+00:00\",\"description\":\"\u26a1 Articulatie coloana de directie METALCAUCHO 00152. Produc\u0103tor: METALCAUCHO. Cod: 00152. Pre\u021b: 32.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/articulatie-coloana-de-directie-metalcaucho-00152\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/articulatie-coloana-de-directie-metalcaucho-00152\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/articulatie-coloana-de-directie-metalcaucho-00152\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/07\\\/3314048_00152_201018.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2026\\\/07\\\/3314048_00152_201018.jpg\",\"width\":600,\"height\":400,\"caption\":\"Articulatie coloana de directie METALCAUCHO 00152 \u2013 RENAULT | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/product\\\/articulatie-coloana-de-directie-metalcaucho-00152\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto RENAULT\",\"item\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Articulatie coloana de directie METALCAUCHO 00152\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/\",\"name\":\"RENAULT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/renault\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Articulatie coloana de directie METALCAUCHO 00152 RENAULT\u2026","description":"\u26a1 Articulatie coloana de directie METALCAUCHO 00152. Produc\u0103tor: METALCAUCHO. Cod: 00152. Pre\u021b: 32.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Articulatie coloana de directie METALCAUCHO 00152 RENAULT | METALCAUCHO - Autorival","og_description":"\u26a1 Articulatie coloana de directie METALCAUCHO 00152. Produc\u0103tor: METALCAUCHO. Cod: 00152. Pre\u021b: 32.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/","og_site_name":"RENAULT","og_image":[{"width":600,"height":400,"url":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3314048_00152_201018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Articulatie coloana de directie METALCAUCHO 00152 RENAULT | METALCAUCHO - Autorival","twitter_description":"\u26a1 Articulatie coloana de directie METALCAUCHO 00152. Produc\u0103tor: METALCAUCHO. Cod: 00152. Pre\u021b: 32.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/","url":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/","name":"Articulatie coloana de directie METALCAUCHO 00152 RENAULT | METALCAUCHO - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/renault\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3314048_00152_201018.jpg","datePublished":"2026-07-31T20:05:17+00:00","description":"\u26a1 Articulatie coloana de directie METALCAUCHO 00152. Produc\u0103tor: METALCAUCHO. Cod: 00152. Pre\u021b: 32.00 RON. \u00cen stoc. Livrare rapid\u0103. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/#primaryimage","url":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3314048_00152_201018.jpg","contentUrl":"https:\/\/autorival.ro\/renault\/wp-content\/uploads\/sites\/23\/2026\/07\/3314048_00152_201018.jpg","width":600,"height":400,"caption":"Articulatie coloana de directie METALCAUCHO 00152 \u2013 RENAULT | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/renault\/product\/articulatie-coloana-de-directie-metalcaucho-00152\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/renault\/"},{"@type":"ListItem","position":2,"name":"Piese auto RENAULT","item":"https:\/\/autorival.ro\/renault\/"},{"@type":"ListItem","position":3,"name":"Articulatie coloana de directie METALCAUCHO 00152"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/renault\/#website","url":"https:\/\/autorival.ro\/renault\/","name":"RENAULT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/renault\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product\/615204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/comments?post=615204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/media\/615205"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/media?parent=615204"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_brand?post=615204"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_cat?post=615204"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/renault\/wp-json\/wp\/v2\/product_tag?post=615204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}