{"id":475082,"date":"2025-07-12T12:32:32","date_gmt":"2025-07-12T12:32:32","guid":{"rendered":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/"},"modified":"2025-07-12T12:32:32","modified_gmt":"2025-07-12T12:32:32","slug":"mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922","status":"publish","type":"product","link":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/","title":{"rendered":"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922"},"content":{"rendered":"<p>Garantie: Garantie 2 aniMasa [g]: 1560Numar articol par: 4.61923<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: DT SPARE PARTS Cod producator: 4.61922<\/p>\n","protected":false},"featured_media":475083,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[186],"product_cat":[32295],"product_tag":[50324,45803,45838,61438,65714,45795,45840,45839],"class_list":{"0":"post-475082","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dt-spare-parts","7":"product_cat-mecanism-actionare-geam-2557-l-diesel-571","8":"product_tag-actionare","9":"product_tag-actros","10":"product_tag-dt","11":"product_tag-geam","12":"product_tag-mecanism","13":"product_tag-mercedes","14":"product_tag-parts","15":"product_tag-spare","17":"first","18":"instock","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 Mercedes | DT - Autorival<\/title>\n<meta name=\"description\" content=\"\u26a1 Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 pentru Mercedes la doar 203.7 RON. \u2713 Cod: 4 \u2713 Brand: DT \u2713 \u00cen stoc \u2713 Livrare 24h \u2713 Garan\u021bie!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 Mercedes | DT - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 pentru Mercedes la doar 203.7 RON. \u2713 Cod: 4 \u2713 Brand: DT \u2713 \u00cen stoc \u2713 Livrare 24h \u2713 Garan\u021bie!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/\" \/>\n<meta property=\"og:site_name\" content=\"Mercedes\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/mercedesbenz\/wp-content\/uploads\/sites\/28\/2025\/07\/4_61922_0-57.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 Mercedes | DT - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 pentru Mercedes la doar 203.7 RON. \u2713 Cod: 4 \u2713 Brand: DT \u2713 \u00cen stoc \u2713 Livrare 24h \u2713 Garan\u021bie!\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/produs\\\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/produs\\\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\\\/\",\"name\":\"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 Mercedes | DT - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/produs\\\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/produs\\\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/07\\\/4_61922_0-57.jpg\",\"datePublished\":\"2025-07-12T12:32:32+00:00\",\"description\":\"\u26a1 Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 pentru Mercedes la doar 203.7 RON. \u2713 Cod: 4 \u2713 Brand: DT \u2713 \u00cen stoc \u2713 Livrare 24h \u2713 Garan\u021bie!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/produs\\\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/produs\\\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/produs\\\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/07\\\/4_61922_0-57.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/07\\\/4_61922_0-57.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/produs\\\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto MERCEDES\",\"item\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/\",\"name\":\"Mercedes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/mercedesbenz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 Mercedes | DT - Autorival","description":"\u26a1 Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 pentru Mercedes la doar 203.7 RON. \u2713 Cod: 4 \u2713 Brand: DT \u2713 \u00cen stoc \u2713 Livrare 24h \u2713 Garan\u021bie!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 Mercedes | DT - Autorival","og_description":"\u26a1 Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 pentru Mercedes la doar 203.7 RON. \u2713 Cod: 4 \u2713 Brand: DT \u2713 \u00cen stoc \u2713 Livrare 24h \u2713 Garan\u021bie!","og_url":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/","og_site_name":"Mercedes","og_image":[{"width":1600,"height":1067,"url":"https:\/\/autorival.ro\/mercedesbenz\/wp-content\/uploads\/sites\/28\/2025\/07\/4_61922_0-57.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 Mercedes | DT - Autorival","twitter_description":"\u26a1 Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 pentru Mercedes la doar 203.7 RON. \u2713 Cod: 4 \u2713 Brand: DT \u2713 \u00cen stoc \u2713 Livrare 24h \u2713 Garan\u021bie!","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/","url":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/","name":"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 Mercedes | DT - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/mercedesbenz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/mercedesbenz\/wp-content\/uploads\/sites\/28\/2025\/07\/4_61922_0-57.jpg","datePublished":"2025-07-12T12:32:32+00:00","description":"\u26a1 Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922 pentru Mercedes la doar 203.7 RON. \u2713 Cod: 4 \u2713 Brand: DT \u2713 \u00cen stoc \u2713 Livrare 24h \u2713 Garan\u021bie!","breadcrumb":{"@id":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/#primaryimage","url":"https:\/\/autorival.ro\/mercedesbenz\/wp-content\/uploads\/sites\/28\/2025\/07\/4_61922_0-57.jpg","contentUrl":"https:\/\/autorival.ro\/mercedesbenz\/wp-content\/uploads\/sites\/28\/2025\/07\/4_61922_0-57.jpg","width":1600,"height":1067,"caption":"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/mercedesbenz\/produs\/mecanism-actionare-geam-mercedes-benz-actros-2557-l-diesel-571-cai-dt-spare-parts-4-61922\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/mercedesbenz\/"},{"@type":"ListItem","position":2,"name":"Piese auto MERCEDES","item":"https:\/\/autorival.ro\/mercedesbenz\/"},{"@type":"ListItem","position":3,"name":"Mecanism actionare geam MERCEDES-BENZ ACTROS 2557 L diesel 571 cai DT SPARE PARTS 4.61922"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/mercedesbenz\/#website","url":"https:\/\/autorival.ro\/mercedesbenz\/","name":"Mercedes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/mercedesbenz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/product\/475082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/comments?post=475082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/media\/475083"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/media?parent=475082"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/product_brand?post=475082"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/product_cat?post=475082"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/mercedesbenz\/wp-json\/wp\/v2\/product_tag?post=475082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}