{"id":1369114,"date":"2026-05-07T08:34:17","date_gmt":"2026-05-07T08:34:17","guid":{"rendered":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/"},"modified":"2026-08-08T12:52:35","modified_gmt":"2026-08-08T12:52:35","slug":"bec-semnalizator-bosch-1-987-301-016","status":"publish","type":"product","link":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/","title":{"rendered":"Bec semnalizator BOSCH 1 987 301 016"},"content":{"rendered":"<p>Bec semnalizator BOSCH 1 987 301 016An fabricatie de la: 200909An fabricatie pana la: 200908Pana la an model: 2009Putere nominal\u0103 [W]: 21\/5Tensiune [V]: 12TIp lampa: P21\/5WVariant\u0103 de execu\u021bie soclu lamp\u0103 incandescent\u0103: BAY15d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: BOSCH Cod producator: 1 987 301 016<\/p>\n","protected":false},"featured_media":1369115,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[848],"product_cat":[],"product_tag":[],"class_list":{"0":"post-1369114","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-bosch","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bec semnalizator BOSCH 1 987 301 016 LAND ROVER | BOSCH\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Bec semnalizator BOSCH 1 987 301 016. Produc\u0103tor: BOSCH. Cod: 1 987 301 016. Pre\u021b: 10.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bec semnalizator BOSCH 1 987 301 016 LAND ROVER | BOSCH - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Bec semnalizator BOSCH 1 987 301 016. Produc\u0103tor: BOSCH. Cod: 1 987 301 016. Pre\u021b: 10.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/\" \/>\n<meta property=\"og:site_name\" content=\"LAND ROVER\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-08T12:52:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/landrover\/wp-content\/uploads\/sites\/19\/2026\/05\/4101241_1987301016drcowhco0000-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"405\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Bec semnalizator BOSCH 1 987 301 016 LAND ROVER | BOSCH - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Bec semnalizator BOSCH 1 987 301 016. Produc\u0103tor: BOSCH. Cod: 1 987 301 016. Pre\u021b: 10.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/product\\\/bec-semnalizator-bosch-1-987-301-016\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/product\\\/bec-semnalizator-bosch-1-987-301-016\\\/\",\"name\":\"Bec semnalizator BOSCH 1 987 301 016 LAND ROVER | BOSCH - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/product\\\/bec-semnalizator-bosch-1-987-301-016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/product\\\/bec-semnalizator-bosch-1-987-301-016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2026\\\/05\\\/4101241_1987301016drcowhco0000-2.jpg\",\"datePublished\":\"2026-05-07T08:34:17+00:00\",\"dateModified\":\"2026-08-08T12:52:35+00:00\",\"description\":\"\u26a1 Bec semnalizator BOSCH 1 987 301 016. Produc\u0103tor: BOSCH. Cod: 1 987 301 016. Pre\u021b: 10.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/product\\\/bec-semnalizator-bosch-1-987-301-016\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/landrover\\\/product\\\/bec-semnalizator-bosch-1-987-301-016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/product\\\/bec-semnalizator-bosch-1-987-301-016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2026\\\/05\\\/4101241_1987301016drcowhco0000-2.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2026\\\/05\\\/4101241_1987301016drcowhco0000-2.jpg\",\"width\":405,\"height\":1024,\"caption\":\"Bec semnalizator BOSCH 1 987 301 016 \u2013 LAND ROVER | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/product\\\/bec-semnalizator-bosch-1-987-301-016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto LAND ROVER\",\"item\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bec semnalizator BOSCH 1 987 301 016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/\",\"name\":\"LAND ROVER\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/landrover\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bec semnalizator BOSCH 1 987 301 016 LAND ROVER | BOSCH\u2026","description":"\u26a1 Bec semnalizator BOSCH 1 987 301 016. Produc\u0103tor: BOSCH. Cod: 1 987 301 016. Pre\u021b: 10.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Bec semnalizator BOSCH 1 987 301 016 LAND ROVER | BOSCH - Autorival","og_description":"\u26a1 Bec semnalizator BOSCH 1 987 301 016. Produc\u0103tor: BOSCH. Cod: 1 987 301 016. Pre\u021b: 10.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/","og_site_name":"LAND ROVER","article_modified_time":"2026-08-08T12:52:35+00:00","og_image":[{"width":405,"height":1024,"url":"https:\/\/autorival.ro\/landrover\/wp-content\/uploads\/sites\/19\/2026\/05\/4101241_1987301016drcowhco0000-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Bec semnalizator BOSCH 1 987 301 016 LAND ROVER | BOSCH - Autorival","twitter_description":"\u26a1 Bec semnalizator BOSCH 1 987 301 016. Produc\u0103tor: BOSCH. Cod: 1 987 301 016. Pre\u021b: 10.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/","url":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/","name":"Bec semnalizator BOSCH 1 987 301 016 LAND ROVER | BOSCH - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/landrover\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/landrover\/wp-content\/uploads\/sites\/19\/2026\/05\/4101241_1987301016drcowhco0000-2.jpg","datePublished":"2026-05-07T08:34:17+00:00","dateModified":"2026-08-08T12:52:35+00:00","description":"\u26a1 Bec semnalizator BOSCH 1 987 301 016. Produc\u0103tor: BOSCH. Cod: 1 987 301 016. Pre\u021b: 10.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/#primaryimage","url":"https:\/\/autorival.ro\/landrover\/wp-content\/uploads\/sites\/19\/2026\/05\/4101241_1987301016drcowhco0000-2.jpg","contentUrl":"https:\/\/autorival.ro\/landrover\/wp-content\/uploads\/sites\/19\/2026\/05\/4101241_1987301016drcowhco0000-2.jpg","width":405,"height":1024,"caption":"Bec semnalizator BOSCH 1 987 301 016 \u2013 LAND ROVER | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/landrover\/product\/bec-semnalizator-bosch-1-987-301-016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/landrover\/"},{"@type":"ListItem","position":2,"name":"Piese auto LAND ROVER","item":"https:\/\/autorival.ro\/landrover\/"},{"@type":"ListItem","position":3,"name":"Bec semnalizator BOSCH 1 987 301 016"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/landrover\/#website","url":"https:\/\/autorival.ro\/landrover\/","name":"LAND ROVER","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/landrover\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/product\/1369114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/comments?post=1369114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/media\/1369115"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/media?parent=1369114"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/product_brand?post=1369114"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/product_cat?post=1369114"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/landrover\/wp-json\/wp\/v2\/product_tag?post=1369114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}