{"id":420253,"date":"2026-06-17T22:02:06","date_gmt":"2026-06-17T22:02:06","guid":{"rendered":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/"},"modified":"2026-06-17T22:02:06","modified_gmt":"2026-06-17T22:02:06","slug":"senzor-nivel-lichid-de-racire-sampa-096-1742","status":"publish","type":"product","link":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/","title":{"rendered":"Senzor nivel lichid de racire SAMPA 096.1742"},"content":{"rendered":"<p>Senzor nivel lichid de racire SAMPA 096.1742Greutate [kg]: 0,099<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: SAMPA Cod producator: 096.1742<\/p>\n","protected":false},"featured_media":420254,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[210],"product_cat":[],"product_tag":[],"class_list":{"0":"post-420253","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-sampa","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senzor nivel lichid de racire SAMPA 096.1742 IVECO | SAMPA\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Senzor nivel lichid de racire SAMPA 096.1742. Produc\u0103tor: SAMPA. Cod: 096.1742. Pre\u021b: 0.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senzor nivel lichid de racire SAMPA 096.1742 IVECO | SAMPA - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Senzor nivel lichid de racire SAMPA 096.1742. Produc\u0103tor: SAMPA. Cod: 096.1742. Pre\u021b: 0.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/\" \/>\n<meta property=\"og:site_name\" content=\"IVECO\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3624159_smpx0961742.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Senzor nivel lichid de racire SAMPA 096.1742 IVECO | SAMPA - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Senzor nivel lichid de racire SAMPA 096.1742. Produc\u0103tor: SAMPA. Cod: 096.1742. Pre\u021b: 0.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/senzor-nivel-lichid-de-racire-sampa-096-1742\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/senzor-nivel-lichid-de-racire-sampa-096-1742\\\/\",\"name\":\"Senzor nivel lichid de racire SAMPA 096.1742 IVECO | SAMPA - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/senzor-nivel-lichid-de-racire-sampa-096-1742\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/senzor-nivel-lichid-de-racire-sampa-096-1742\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/3624159_smpx0961742.jpg\",\"datePublished\":\"2026-06-17T22:02:06+00:00\",\"description\":\"\u26a1 Senzor nivel lichid de racire SAMPA 096.1742. Produc\u0103tor: SAMPA. Cod: 096.1742. Pre\u021b: 0.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/senzor-nivel-lichid-de-racire-sampa-096-1742\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/senzor-nivel-lichid-de-racire-sampa-096-1742\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/senzor-nivel-lichid-de-racire-sampa-096-1742\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/3624159_smpx0961742.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/3624159_smpx0961742.jpg\",\"width\":600,\"height\":400,\"caption\":\"Senzor nivel lichid de racire SAMPA 096.1742 \u2013 IVECO | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/senzor-nivel-lichid-de-racire-sampa-096-1742\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto IVECO\",\"item\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senzor nivel lichid de racire SAMPA 096.1742\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\",\"name\":\"IVECO\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senzor nivel lichid de racire SAMPA 096.1742 IVECO | SAMPA\u2026","description":"\u26a1 Senzor nivel lichid de racire SAMPA 096.1742. Produc\u0103tor: SAMPA. Cod: 096.1742. Pre\u021b: 0.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Senzor nivel lichid de racire SAMPA 096.1742 IVECO | SAMPA - Autorival","og_description":"\u26a1 Senzor nivel lichid de racire SAMPA 096.1742. Produc\u0103tor: SAMPA. Cod: 096.1742. Pre\u021b: 0.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/","og_site_name":"IVECO","og_image":[{"width":600,"height":400,"url":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3624159_smpx0961742.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Senzor nivel lichid de racire SAMPA 096.1742 IVECO | SAMPA - Autorival","twitter_description":"\u26a1 Senzor nivel lichid de racire SAMPA 096.1742. Produc\u0103tor: SAMPA. Cod: 096.1742. Pre\u021b: 0.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/","url":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/","name":"Senzor nivel lichid de racire SAMPA 096.1742 IVECO | SAMPA - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/iveco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3624159_smpx0961742.jpg","datePublished":"2026-06-17T22:02:06+00:00","description":"\u26a1 Senzor nivel lichid de racire SAMPA 096.1742. Produc\u0103tor: SAMPA. Cod: 096.1742. Pre\u021b: 0.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/#primaryimage","url":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3624159_smpx0961742.jpg","contentUrl":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3624159_smpx0961742.jpg","width":600,"height":400,"caption":"Senzor nivel lichid de racire SAMPA 096.1742 \u2013 IVECO | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/iveco\/product\/senzor-nivel-lichid-de-racire-sampa-096-1742\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/iveco\/"},{"@type":"ListItem","position":2,"name":"Piese auto IVECO","item":"https:\/\/autorival.ro\/iveco\/"},{"@type":"ListItem","position":3,"name":"Senzor nivel lichid de racire SAMPA 096.1742"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/iveco\/#website","url":"https:\/\/autorival.ro\/iveco\/","name":"IVECO","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/iveco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product\/420253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/comments?post=420253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/media\/420254"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/media?parent=420253"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_brand?post=420253"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_cat?post=420253"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_tag?post=420253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}