{"id":418404,"date":"2026-06-17T21:58:24","date_gmt":"2026-06-17T21:58:24","guid":{"rendered":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/"},"modified":"2026-06-17T21:58:24","modified_gmt":"2026-06-17T21:58:24","slug":"rola-ghidare-conducere-curea-transmisie-kamoka-r0261","status":"publish","type":"product","link":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/","title":{"rendered":"Rola ghidare \/ conducere curea transmisie KAMOKA R0261"},"content":{"rendered":"<p>Rola ghidare \/ conducere curea transmisie KAMOKA R0261Agregate angrenate: AlternatorDiametru exterior [mm]: 70Latime [mm]: 29<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: KAMOKA Cod producator: R0261<\/p>\n","protected":false},"featured_media":418405,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[1241],"product_cat":[],"product_tag":[],"class_list":{"0":"post-418404","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-kamoka","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rola ghidare \/ conducere curea transmisie KAMOKA R0261 IVECO\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Rola ghidare \/ conducere curea transmisie KAMOKA R0261. Produc\u0103tor: KAMOKA. Cod: R0261. Pre\u021b: 56 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rola ghidare \/ conducere curea transmisie KAMOKA R0261 IVECO | KAMOKA - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Rola ghidare \/ conducere curea transmisie KAMOKA R0261. Produc\u0103tor: KAMOKA. Cod: R0261. Pre\u021b: 56 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/\" \/>\n<meta property=\"og:site_name\" content=\"IVECO\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/2209664_r0261_a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Rola ghidare \/ conducere curea transmisie KAMOKA R0261 IVECO | KAMOKA - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Rola ghidare \/ conducere curea transmisie KAMOKA R0261. Produc\u0103tor: KAMOKA. Cod: R0261. Pre\u021b: 56 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\\\/\",\"name\":\"Rola ghidare \\\/ conducere curea transmisie KAMOKA R0261 IVECO | KAMOKA - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/2209664_r0261_a.jpg\",\"datePublished\":\"2026-06-17T21:58:24+00:00\",\"description\":\"\u26a1 Rola ghidare \\\/ conducere curea transmisie KAMOKA R0261. Produc\u0103tor: KAMOKA. Cod: R0261. Pre\u021b: 56 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/2209664_r0261_a.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/2209664_r0261_a.jpg\",\"width\":600,\"height\":400,\"caption\":\"Rola ghidare \\\/ conducere curea transmisie KAMOKA R0261 \u2013 IVECO | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto IVECO\",\"item\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rola ghidare \\\/ conducere curea transmisie KAMOKA R0261\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\",\"name\":\"IVECO\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rola ghidare \/ conducere curea transmisie KAMOKA R0261 IVECO\u2026","description":"\u26a1 Rola ghidare \/ conducere curea transmisie KAMOKA R0261. Produc\u0103tor: KAMOKA. Cod: R0261. Pre\u021b: 56 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Rola ghidare \/ conducere curea transmisie KAMOKA R0261 IVECO | KAMOKA - Autorival","og_description":"\u26a1 Rola ghidare \/ conducere curea transmisie KAMOKA R0261. Produc\u0103tor: KAMOKA. Cod: R0261. Pre\u021b: 56 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/","og_site_name":"IVECO","og_image":[{"width":600,"height":400,"url":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/2209664_r0261_a.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Rola ghidare \/ conducere curea transmisie KAMOKA R0261 IVECO | KAMOKA - Autorival","twitter_description":"\u26a1 Rola ghidare \/ conducere curea transmisie KAMOKA R0261. Produc\u0103tor: KAMOKA. Cod: R0261. Pre\u021b: 56 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/","url":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/","name":"Rola ghidare \/ conducere curea transmisie KAMOKA R0261 IVECO | KAMOKA - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/iveco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/2209664_r0261_a.jpg","datePublished":"2026-06-17T21:58:24+00:00","description":"\u26a1 Rola ghidare \/ conducere curea transmisie KAMOKA R0261. Produc\u0103tor: KAMOKA. Cod: R0261. Pre\u021b: 56 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/#primaryimage","url":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/2209664_r0261_a.jpg","contentUrl":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/2209664_r0261_a.jpg","width":600,"height":400,"caption":"Rola ghidare \/ conducere curea transmisie KAMOKA R0261 \u2013 IVECO | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/iveco\/product\/rola-ghidare-conducere-curea-transmisie-kamoka-r0261\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/iveco\/"},{"@type":"ListItem","position":2,"name":"Piese auto IVECO","item":"https:\/\/autorival.ro\/iveco\/"},{"@type":"ListItem","position":3,"name":"Rola ghidare \/ conducere curea transmisie KAMOKA R0261"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/iveco\/#website","url":"https:\/\/autorival.ro\/iveco\/","name":"IVECO","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/iveco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product\/418404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/comments?post=418404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/media\/418405"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/media?parent=418404"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_brand?post=418404"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_cat?post=418404"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_tag?post=418404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}