{"id":402189,"date":"2026-06-17T21:28:24","date_gmt":"2026-06-17T21:28:24","guid":{"rendered":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/"},"modified":"2026-06-17T21:28:24","modified_gmt":"2026-06-17T21:28:24","slug":"coroana-dintata-volanta-sampa-065-060","status":"publish","type":"product","link":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/","title":{"rendered":"Coroana dintata volanta SAMPA 065.060"},"content":{"rendered":"<p>Coroana dintata volanta SAMPA 065.060Diametru exterior [mm]: 479Diametru interior [mm]: 436Greutate [kg]: 4,431Numar dinti: 149<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: SAMPA Cod producator: 065.060<\/p>\n","protected":false},"featured_media":402190,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[210],"product_cat":[],"product_tag":[],"class_list":{"0":"post-402189","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-sampa","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coroana dintata volanta SAMPA 065.060 IVECO | SAMPA - Autorival<\/title>\n<meta name=\"description\" content=\"\u26a1 Coroana dintata volanta SAMPA 065.060. Produc\u0103tor: SAMPA. Cod: 065.060. Pre\u021b: 169.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coroana dintata volanta SAMPA 065.060 IVECO | SAMPA - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Coroana dintata volanta SAMPA 065.060. Produc\u0103tor: SAMPA. Cod: 065.060. Pre\u021b: 169.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/\" \/>\n<meta property=\"og:site_name\" content=\"IVECO\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3610943_smpx065060.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coroana dintata volanta SAMPA 065.060 IVECO | SAMPA - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Coroana dintata volanta SAMPA 065.060. Produc\u0103tor: SAMPA. Cod: 065.060. Pre\u021b: 169.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/coroana-dintata-volanta-sampa-065-060\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/coroana-dintata-volanta-sampa-065-060\\\/\",\"name\":\"Coroana dintata volanta SAMPA 065.060 IVECO | SAMPA - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/coroana-dintata-volanta-sampa-065-060\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/coroana-dintata-volanta-sampa-065-060\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/3610943_smpx065060.jpg\",\"datePublished\":\"2026-06-17T21:28:24+00:00\",\"description\":\"\u26a1 Coroana dintata volanta SAMPA 065.060. Produc\u0103tor: SAMPA. Cod: 065.060. Pre\u021b: 169.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/coroana-dintata-volanta-sampa-065-060\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/coroana-dintata-volanta-sampa-065-060\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/coroana-dintata-volanta-sampa-065-060\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/3610943_smpx065060.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/06\\\/3610943_smpx065060.jpg\",\"width\":600,\"height\":400,\"caption\":\"Coroana dintata volanta SAMPA 065.060 \u2013 IVECO | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/product\\\/coroana-dintata-volanta-sampa-065-060\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto IVECO\",\"item\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Coroana dintata volanta SAMPA 065.060\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/\",\"name\":\"IVECO\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/iveco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coroana dintata volanta SAMPA 065.060 IVECO | SAMPA - Autorival","description":"\u26a1 Coroana dintata volanta SAMPA 065.060. Produc\u0103tor: SAMPA. Cod: 065.060. Pre\u021b: 169.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Coroana dintata volanta SAMPA 065.060 IVECO | SAMPA - Autorival","og_description":"\u26a1 Coroana dintata volanta SAMPA 065.060. Produc\u0103tor: SAMPA. Cod: 065.060. Pre\u021b: 169.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/","og_site_name":"IVECO","og_image":[{"width":600,"height":400,"url":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3610943_smpx065060.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Coroana dintata volanta SAMPA 065.060 IVECO | SAMPA - Autorival","twitter_description":"\u26a1 Coroana dintata volanta SAMPA 065.060. Produc\u0103tor: SAMPA. Cod: 065.060. Pre\u021b: 169.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/","url":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/","name":"Coroana dintata volanta SAMPA 065.060 IVECO | SAMPA - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/iveco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3610943_smpx065060.jpg","datePublished":"2026-06-17T21:28:24+00:00","description":"\u26a1 Coroana dintata volanta SAMPA 065.060. Produc\u0103tor: SAMPA. Cod: 065.060. Pre\u021b: 169.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/#primaryimage","url":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3610943_smpx065060.jpg","contentUrl":"https:\/\/autorival.ro\/iveco\/wp-content\/uploads\/sites\/13\/2026\/06\/3610943_smpx065060.jpg","width":600,"height":400,"caption":"Coroana dintata volanta SAMPA 065.060 \u2013 IVECO | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/iveco\/product\/coroana-dintata-volanta-sampa-065-060\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/iveco\/"},{"@type":"ListItem","position":2,"name":"Piese auto IVECO","item":"https:\/\/autorival.ro\/iveco\/"},{"@type":"ListItem","position":3,"name":"Coroana dintata volanta SAMPA 065.060"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/iveco\/#website","url":"https:\/\/autorival.ro\/iveco\/","name":"IVECO","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/iveco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product\/402189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/comments?post=402189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/media\/402190"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/media?parent=402189"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_brand?post=402189"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_cat?post=402189"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/iveco\/wp-json\/wp\/v2\/product_tag?post=402189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}