{"id":383074,"date":"2026-05-08T08:25:27","date_gmt":"2026-05-08T08:25:27","guid":{"rendered":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/"},"modified":"2026-05-08T08:25:27","modified_gmt":"2026-05-08T08:25:27","slug":"unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950","status":"publish","type":"product","link":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/","title":{"rendered":"Unitate de injectie regenerare filtru de particule HOFFER H1950"},"content":{"rendered":"<p>Unitate de injectie regenerare filtru de particule HOFFER H1950pt. cod original (OE): 2022247<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: HOFFER Cod producator: H1950<\/p>\n","protected":false},"featured_media":383075,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[7009],"product_cat":[],"product_tag":[],"class_list":{"0":"post-383074","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-hoffer","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unitate de injectie regenerare filtru de particule HOFFER H1950\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Unitate de injectie regenerare filtru de particule HOFFER H1950. Produc\u0103tor: HOFFER. Cod: H1950. Pre\u021b: 1096.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unitate de injectie regenerare filtru de particule HOFFER H1950 FORD | HOFFER - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Unitate de injectie regenerare filtru de particule HOFFER H1950. Produc\u0103tor: HOFFER. Cod: H1950. Pre\u021b: 1096.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/\" \/>\n<meta property=\"og:site_name\" content=\"FORD\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/ford\/wp-content\/uploads\/sites\/3\/2026\/05\/2553313_h_152979.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Unitate de injectie regenerare filtru de particule HOFFER H1950 FORD | HOFFER - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Unitate de injectie regenerare filtru de particule HOFFER H1950. Produc\u0103tor: HOFFER. Cod: H1950. Pre\u021b: 1096.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/product\\\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/product\\\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\\\/\",\"name\":\"Unitate de injectie regenerare filtru de particule HOFFER H1950 FORD | HOFFER - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/product\\\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/product\\\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/05\\\/2553313_h_152979.jpg\",\"datePublished\":\"2026-05-08T08:25:27+00:00\",\"description\":\"\u26a1 Unitate de injectie regenerare filtru de particule HOFFER H1950. Produc\u0103tor: HOFFER. Cod: H1950. Pre\u021b: 1096.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/product\\\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/ford\\\/product\\\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/product\\\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/05\\\/2553313_h_152979.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/05\\\/2553313_h_152979.jpg\",\"width\":400,\"height\":400,\"caption\":\"Unitate de injectie regenerare filtru de particule HOFFER H1950 \u2013 FORD | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/product\\\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto FORD\",\"item\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unitate de injectie regenerare filtru de particule HOFFER H1950\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/\",\"name\":\"FORD\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/ford\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unitate de injectie regenerare filtru de particule HOFFER H1950\u2026","description":"\u26a1 Unitate de injectie regenerare filtru de particule HOFFER H1950. Produc\u0103tor: HOFFER. Cod: H1950. Pre\u021b: 1096.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Unitate de injectie regenerare filtru de particule HOFFER H1950 FORD | HOFFER - Autorival","og_description":"\u26a1 Unitate de injectie regenerare filtru de particule HOFFER H1950. Produc\u0103tor: HOFFER. Cod: H1950. Pre\u021b: 1096.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/","og_site_name":"FORD","og_image":[{"width":400,"height":400,"url":"https:\/\/autorival.ro\/ford\/wp-content\/uploads\/sites\/3\/2026\/05\/2553313_h_152979.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Unitate de injectie regenerare filtru de particule HOFFER H1950 FORD | HOFFER - Autorival","twitter_description":"\u26a1 Unitate de injectie regenerare filtru de particule HOFFER H1950. Produc\u0103tor: HOFFER. Cod: H1950. Pre\u021b: 1096.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/","url":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/","name":"Unitate de injectie regenerare filtru de particule HOFFER H1950 FORD | HOFFER - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/ford\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/ford\/wp-content\/uploads\/sites\/3\/2026\/05\/2553313_h_152979.jpg","datePublished":"2026-05-08T08:25:27+00:00","description":"\u26a1 Unitate de injectie regenerare filtru de particule HOFFER H1950. Produc\u0103tor: HOFFER. Cod: H1950. Pre\u021b: 1096.00 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/#primaryimage","url":"https:\/\/autorival.ro\/ford\/wp-content\/uploads\/sites\/3\/2026\/05\/2553313_h_152979.jpg","contentUrl":"https:\/\/autorival.ro\/ford\/wp-content\/uploads\/sites\/3\/2026\/05\/2553313_h_152979.jpg","width":400,"height":400,"caption":"Unitate de injectie regenerare filtru de particule HOFFER H1950 \u2013 FORD | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/ford\/product\/unitate-de-injectie-regenerare-filtru-de-particule-hoffer-h1950\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/ford\/"},{"@type":"ListItem","position":2,"name":"Piese auto FORD","item":"https:\/\/autorival.ro\/ford\/"},{"@type":"ListItem","position":3,"name":"Unitate de injectie regenerare filtru de particule HOFFER H1950"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/ford\/#website","url":"https:\/\/autorival.ro\/ford\/","name":"FORD","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/ford\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/product\/383074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/comments?post=383074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/media\/383075"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/media?parent=383074"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/product_brand?post=383074"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/product_cat?post=383074"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/ford\/wp-json\/wp\/v2\/product_tag?post=383074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}