{"id":589166,"date":"2026-07-23T11:37:42","date_gmt":"2026-07-23T11:37:42","guid":{"rendered":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/"},"modified":"2026-09-01T09:32:50","modified_gmt":"2026-09-01T06:32:50","slug":"senzor-pozitie-clapeta-acceleratie-hella-6px008476-331","status":"publish","type":"product","link":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/","title":{"rendered":"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331"},"content":{"rendered":"<p>An fabricatie de la: 199507An fabricatie pana la: 199506De la nr. VET: 0006780Forma carcasa stecher: dreptunghiularNum\u0103rul conexiunilor cu muf\u0103: 3Pana la nr. VET: 0006779Tensiune [V]: 12Tip senzor: potentiometru semireglabil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producator: HELLA Cod producator: 6PX008476-331<\/p>\n","protected":false},"featured_media":589167,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-589166","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 FIAT\u2026<\/title>\n<meta name=\"description\" content=\"\u26a1 Senzor pozitie clapeta acceleratie HELLA 6PX008476-331. Produc\u0103tor: HELLA. Cod: 6PX008476-331. Pre\u021b: 82 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 FIAT | Cod - Autorival\" \/>\n<meta property=\"og:description\" content=\"\u26a1 Senzor pozitie clapeta acceleratie HELLA 6PX008476-331. Produc\u0103tor: HELLA. Cod: 6PX008476-331. Pre\u021b: 82 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/\" \/>\n<meta property=\"og:site_name\" content=\"FIAT\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T06:32:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autorival.ro\/fiat\/wp-content\/uploads\/sites\/9\/2026\/07\/3884460_6px_008_476-331.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 FIAT | Cod - Autorival\" \/>\n<meta name=\"twitter:description\" content=\"\u26a1 Senzor pozitie clapeta acceleratie HELLA 6PX008476-331. Produc\u0103tor: HELLA. Cod: 6PX008476-331. Pre\u021b: 82 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/product\\\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\\\/\",\"url\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/product\\\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\\\/\",\"name\":\"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 FIAT | Cod - Autorival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/product\\\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/product\\\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2026\\\/07\\\/3884460_6px_008_476-331.jpg\",\"datePublished\":\"2026-07-23T11:37:42+00:00\",\"dateModified\":\"2026-09-01T06:32:50+00:00\",\"description\":\"\u26a1 Senzor pozitie clapeta acceleratie HELLA 6PX008476-331. Produc\u0103tor: HELLA. Cod: 6PX008476-331. Pre\u021b: 82 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/product\\\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autorival.ro\\\/fiat\\\/product\\\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/product\\\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2026\\\/07\\\/3884460_6px_008_476-331.jpg\",\"contentUrl\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2026\\\/07\\\/3884460_6px_008_476-331.jpg\",\"width\":600,\"height\":400,\"caption\":\"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 \u2013 FIAT | AutoRival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/product\\\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piese auto FIAT\",\"item\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/#website\",\"url\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/\",\"name\":\"FIAT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autorival.ro\\\/fiat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 FIAT\u2026","description":"\u26a1 Senzor pozitie clapeta acceleratie HELLA 6PX008476-331. Produc\u0103tor: HELLA. Cod: 6PX008476-331. Pre\u021b: 82 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ro_RO","og_type":"article","og_title":"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 FIAT | Cod - Autorival","og_description":"\u26a1 Senzor pozitie clapeta acceleratie HELLA 6PX008476-331. Produc\u0103tor: HELLA. Cod: 6PX008476-331. Pre\u021b: 82 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","og_url":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/","og_site_name":"FIAT","article_modified_time":"2026-09-01T06:32:50+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/autorival.ro\/fiat\/wp-content\/uploads\/sites\/9\/2026\/07\/3884460_6px_008_476-331.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 FIAT | Cod - Autorival","twitter_description":"\u26a1 Senzor pozitie clapeta acceleratie HELLA 6PX008476-331. Produc\u0103tor: HELLA. Cod: 6PX008476-331. Pre\u021b: 82 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/","url":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/","name":"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 FIAT | Cod - Autorival","isPartOf":{"@id":"https:\/\/autorival.ro\/fiat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/#primaryimage"},"image":{"@id":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/#primaryimage"},"thumbnailUrl":"https:\/\/autorival.ro\/fiat\/wp-content\/uploads\/sites\/9\/2026\/07\/3884460_6px_008_476-331.jpg","datePublished":"2026-07-23T11:37:42+00:00","dateModified":"2026-09-01T06:32:50+00:00","description":"\u26a1 Senzor pozitie clapeta acceleratie HELLA 6PX008476-331. Produc\u0103tor: HELLA. Cod: 6PX008476-331. Pre\u021b: 82 RON. \u00cen stoc. Livrare 24h. Garan\u021bie.","breadcrumb":{"@id":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/#primaryimage","url":"https:\/\/autorival.ro\/fiat\/wp-content\/uploads\/sites\/9\/2026\/07\/3884460_6px_008_476-331.jpg","contentUrl":"https:\/\/autorival.ro\/fiat\/wp-content\/uploads\/sites\/9\/2026\/07\/3884460_6px_008_476-331.jpg","width":600,"height":400,"caption":"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331 \u2013 FIAT | AutoRival"},{"@type":"BreadcrumbList","@id":"https:\/\/autorival.ro\/fiat\/product\/senzor-pozitie-clapeta-acceleratie-hella-6px008476-331\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/autorival.ro\/fiat\/"},{"@type":"ListItem","position":2,"name":"Piese auto FIAT","item":"https:\/\/autorival.ro\/fiat\/"},{"@type":"ListItem","position":3,"name":"Senzor pozitie clapeta acceleratie HELLA 6PX008476-331"}]},{"@type":"WebSite","@id":"https:\/\/autorival.ro\/fiat\/#website","url":"https:\/\/autorival.ro\/fiat\/","name":"FIAT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autorival.ro\/fiat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/product\/589166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/comments?post=589166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/media\/589167"}],"wp:attachment":[{"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/media?parent=589166"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/product_brand?post=589166"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/product_cat?post=589166"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autorival.ro\/fiat\/wp-json\/wp\/v2\/product_tag?post=589166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}